{"id":119930,"date":"2023-03-05T09:47:17","date_gmt":"2023-03-05T07:47:17","guid":{"rendered":"https:\/\/www.thegfrecipes.com\/informativa-sulla-privacy\/"},"modified":"2024-08-17T01:41:10","modified_gmt":"2024-08-16T23:41:10","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/www.thegfrecipes.com\/it\/informativa-sulla-privacy","title":{"rendered":"Informativa sulla Privacy"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Aggiornato al 2024-08-14<\/h4>\n\n<p class=\"wp-block-paragraph\">The GF Recipes (&#8220;noi&#8221;, &#8220;nostro&#8221; o &#8220;ci&#8221;) si impegna a proteggere la vostra privacy. La presente Informativa sulla privacy spiega come i vostri dati personali vengono raccolti, utilizzati e divulgati da The GF Recipes. <\/p>\n\n<p class=\"wp-block-paragraph\">Questa Informativa sulla Privacy si applica al nostro sito web e ai suoi sottodomini associati (collettivamente, il nostro &#8220;Servizio&#8221;), insieme alla nostra applicazione, The GF Recipes. Accedendo o utilizzando il nostro Servizio, dichiari di aver letto, compreso e accettato la nostra raccolta, conservazione, utilizzo e divulgazione delle tue informazioni personali come descritto in questa Informativa sulla Privacy e nei nostri Termini di Servizio.  <\/p>\n\n<h1 class=\"wp-block-heading\">Definizioni e termini chiave<\/h1>\n\n<p class=\"wp-block-paragraph\">Per aiutare a spiegare le cose nel modo pi\u00f9 chiaro possibile in questa Informativa sulla Privacy, ogni volta che uno di questi termini viene citato, \u00e8 rigorosamente definito come segue:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cookie: piccola quantit\u00e0 di dati generati da un sito web e salvati dal tuo browser web. Viene utilizzato per identificare il tuo browser, fornire analisi, ricordare informazioni su di te come le tue preferenze linguistiche o le informazioni di accesso. <\/li>\n\n\n\n<li>Societ\u00e0: quando questa politica menziona &#8220;Societ\u00e0,&#8221; &#8220;noi,&#8221; &#8220;ci&#8221; o &#8220;nostro,&#8221; si riferisce a Exponential Financial Consult S.R.L., Strada Gheorghe Doja, Nr. 1, Blocco 37D, Piano 1, App. 36, Ploiesti, Judet Prahova, Romania, che \u00e8 responsabile delle tue informazioni in base a questa Informativa sulla Privacy. <\/li>\n\n\n\n<li>Paese: dove ha sede The GF Recipes o i proprietari\/fondatori di The GF Recipes, in questo caso la Romania.<\/li>\n\n\n\n<li>Cliente: si riferisce all&#8217;azienda, all&#8217;organizzazione o alla persona che si iscrive al Servizio &#8220;Le Ricette GF&#8221; per gestire i rapporti con i vostri consumatori o utenti del servizio.ania<\/li>\n\n\n\n<li>Dispositivo: qualsiasi dispositivo connesso a Internet come un telefono, tablet, computer o qualsiasi altro dispositivo che pu\u00f2 essere utilizzato per visitare The GF Recipes e utilizzare i servizi.<\/li>\n\n\n\n<li>Indirizzo IP: A ogni dispositivo connesso a Internet viene assegnato un numero noto come indirizzo di protocollo Internet (IP). Questi numeri sono solitamente assegnati in blocchi geografici. Un indirizzo IP pu\u00f2 spesso essere utilizzato per identificare la posizione da cui un dispositivo si connette a Internet.  <\/li>\n\n\n\n<li>Personale: si riferisce a quegli individui che sono impiegati da The GF Recipes o sono sotto contratto per svolgere un servizio per conto di una delle parti.<\/li>\n\n\n\n<li>Dati personali: qualsiasi informazione che direttamente, indirettamente o in connessione con altre informazioni &#8211; compreso un numero di identificazione personale &#8211; consenta l&#8217;identificazione o l&#8217;identificabilit\u00e0 di una persona fisica.<\/li>\n\n\n\n<li>Servizio: si riferisce al servizio fornito da The GF Recipes come descritto nei relativi termini (se disponibili) e su questa piattaforma.<\/li>\n\n\n\n<li>Servizio di terze parti: si riferisce agli inserzionisti, ai sponsor dei concorsi, ai partner promozionali e di marketing e ad altri che forniscono i nostri contenuti o i cui prodotti o servizi riteniamo possano interessarti.<\/li>\n\n\n\n<li>Sito web: il sito di The GF Recipes, accessibile tramite questo URL: http:\/\/thegfrecipes.com\/?lang=it<\/li>\n\n\n\n<li>Utente: persona o entit\u00e0 che si \u00e8 registrata presso The GF Recipes per utilizzare i Servizi.<\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Quali informazioni raccogliamo?<\/h1>\n\n<p class=\"wp-block-paragraph\">Raccogliamo informazioni dall&#8217;utente quando visita il nostro sito\/app, si registra sul nostro sito, effettua un ordine, si iscrive alla nostra newsletter, risponde a un sondaggio o compila un modulo.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Nome \/ Nome utente<\/li>\n\n\n\n<li>Indirizzi e-mail<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Dati di accesso ai social media<\/strong>. Potremmo offrirti la possibilit\u00e0 di registrarti con noi utilizzando i dati del tuo account di social media esistente, come il tuo account Google, Apple o di altri social media. Se<br\/>scegli di registrarti in questo modo, raccoglieremo alcune informazioni sul tuo profilo dal provider del social media, come descritto nella sezione &#8220;COME GESTIAMO I TUOI LOGIN SOCIAL<br\/>?&#8221; di seguito.  <\/p>\n\n<p class=\"wp-block-paragraph\">Raccogliamo anche informazioni dai dispositivi mobili per migliorare l&#8217;esperienza dell&#8217;utente, anche se queste funzioni sono del tutto facoltative:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Posizione (GPS): I dati sulla posizione aiutano a creare una rappresentazione accurata dei tuoi interessi e possono essere utilizzati per proporre annunci pi\u00f9 mirati e pertinenti ai potenziali clienti.<\/li>\n\n\n\n<li>Dati del dispositivo mobile. Raccogliamo automaticamente informazioni sul dispositivo (come l&#8217;ID del dispositivo mobile, il modello e il produttore), il sistema operativo, le informazioni sulla versione e le informazioni sulla configurazione del sistema<br\/>, i numeri di identificazione del dispositivo e dell&#8217;applicazione, il tipo e la versione del browser:<br\/>Se stai utilizzando le nostre applicazioni, potremmo anche raccogliere informazioni sulla rete telefonica associata al tuo dispositivo mobile, sul sistema operativo o sulla piattaforma del tuo<br\/>dispositivo mobile, sul tipo di dispositivo mobile che utilizzi, sull&#8217;ID univoco del tuo dispositivo mobile e sulle informazioni relative alle funzionalit\u00e0 delle nostre applicazioni a cui hai<br\/>avuto accesso. <\/li>\n\n\n\n<li>Notifiche push. Potremmo chiederti di inviarti notifiche push relative al tuo account o a determinate funzionalit\u00e0 delle applicazioni. Se desideri evitare di ricevere questo tipo di comunicazioni su<br\/>, puoi disattivarle nelle impostazioni del tuo dispositivo.  <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Queste informazioni sono necessarie principalmente per mantenere la sicurezza e il funzionamento delle nostre applicazioni, per la risoluzione dei problemi e per i nostri scopi interni di analisi e reporting. Tutti i dati personali forniti dall&#8217;utente devono essere veritieri, completi e accurati e l&#8217;utente \u00e8 tenuto a comunicarci qualsiasi modifica di tali dati personali. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Informazioni sensibili<\/strong>. Quando necessario, con il tuo consenso o come altrimenti consentito dalla legge applicabile, trattiamo le seguenti categorie di informazioni sensibili: <\/p>\n\n<p class=\"wp-block-paragraph\">&#8211; Dati sanitari<br\/><br\/><strong>Google API<\/strong> &#8211; Il nostro utilizzo delle informazioni ricevute dalle API di Google sar\u00e0 conforme alle <a href=\"https:\/\/developers.google.com\/terms\/api-services-user-data-policy\" target=\"_blank\" rel=\"noopener\">Norme sui dati degli utenti dei servizi API di Google<\/a>, compresi i <a href=\"https:\/\/developers.google.com\/terms\/api-services-user-data-policy#limited-use\" target=\"_blank\" rel=\"noopener\">requisiti di IJse limitato<\/a>.<\/p>\n\n<h1 class=\"wp-block-heading\">Come utilizziamo le informazioni raccolte?<\/h1>\n\n<p class=\"wp-block-paragraph\">Tutte le informazioni che raccogliamo dall&#8217;utente possono essere utilizzate in uno dei seguenti modi:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Per personalizzare la vostra esperienza (le vostre informazioni ci aiutano a rispondere meglio alle vostre esigenze individuali)<\/li>\n\n\n\n<li>Per migliorare il nostro sito web\/app (ci sforziamo continuamente di migliorare le nostre offerte di sito web\/app sulla base delle informazioni e dei feedback che riceviamo da voi)<\/li>\n\n\n\n<li>Per migliorare il servizio clienti (le vostre informazioni ci aiutano a rispondere in modo pi\u00f9 efficace alle vostre richieste di assistenza e supporto)<\/li>\n\n\n\n<li>Per processare le transazioni<\/li>\n\n\n\n<li>Per amministrare un concorso, una promozione, un sondaggio o un&#8217;altra funzione del sito<\/li>\n\n\n\n<li>Per inviare e-mail periodiche<\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Quando The GF Recipes utilizza le informazioni degli utenti finali provenienti da terzi?<\/h1>\n\n<p class=\"wp-block-paragraph\">The GF Recipes raccoglier\u00e0 i Dati dell&#8217;Utente Finale necessari per fornire i servizi di The GF Recipes ai nostri clienti.<\/p>\n\n<p class=\"wp-block-paragraph\">Gli utenti finali possono fornirci volontariamente le informazioni che hanno reso disponibili sui siti web dei social media. Se l&#8217;utente ci fornisce tali informazioni, possiamo raccogliere le informazioni disponibili pubblicamente dai siti web dei social media indicati dall&#8217;utente. L&#8217;utente pu\u00f2 controllare la quantit\u00e0 di informazioni rese pubbliche dai siti web dei social media visitando tali siti e modificando le impostazioni sulla privacy.  <\/p>\n\n<h1 class=\"wp-block-heading\">Quando The GF Recipes utilizza le informazioni dei clienti provenienti da terzi?<\/h1>\n\n<p class=\"wp-block-paragraph\">Riceviamo alcune informazioni da terzi quando ci contattate. Ad esempio, quando ci inviate il vostro indirizzo e-mail per dimostrare interesse a diventare clienti di The GF Recipes, riceviamo informazioni da una terza parte che fornisce servizi di rilevamento automatico delle frodi a The GF Recipes. Occasionalmente raccogliamo anche informazioni rese pubbliche sui siti web dei social media. L&#8217;utente pu\u00f2 controllare la quantit\u00e0 di informazioni rese pubbliche dai siti web dei social media visitando tali siti e modificando le impostazioni sulla privacy.   <\/p>\n\n<h1 class=\"wp-block-heading\">Condividiamo le informazioni raccolte con terzi?<\/h1>\n\n<p class=\"wp-block-paragraph\">Possiamo condividere le informazioni che raccogliamo, sia personali che non personali, con terze parti quali inserzionisti, sponsor di concorsi, partner promozionali e di marketing e altri soggetti che forniscono i nostri contenuti o i cui prodotti o servizi riteniamo possano interessarvi. Potremmo anche condividerle con le nostre societ\u00e0 affiliate e i nostri partner commerciali attuali e futuri e, nel caso in cui fossimo coinvolti in una fusione, in una vendita di attivit\u00e0 o in un&#8217;altra riorganizzazione aziendale, potremmo anche condividere o trasferire le vostre informazioni personali e non personali ai nostri successori. <\/p>\n\n<p class=\"wp-block-paragraph\">Possiamo ingaggiare fornitori di servizi terzi di fiducia per svolgere funzioni e fornire servizi, come l&#8217;hosting e la manutenzione dei nostri server e del sito web\/app, l&#8217;archiviazione e la gestione dei database, la gestione delle e-mail, il marketing di archiviazione, l&#8217;elaborazione delle carte di credito, l&#8217;assistenza clienti e l&#8217;evasione degli ordini per i prodotti e i servizi che potete acquistare attraverso il sito web\/app. \u00c8 probabile che condivideremo le vostre informazioni personali, ed eventualmente alcune informazioni non personali, con queste terze parti per consentire loro di svolgere questi servizi per noi e per voi. <\/p>\n\n<p class=\"wp-block-paragraph\">Possiamo condividere parte dei dati dei nostri file di log, compresi gli indirizzi IP, per scopi analitici con terze parti, quali partner di analisi web, sviluppatori di applicazioni e reti pubblicitarie. Se il vostro indirizzo IP viene condiviso, pu\u00f2 essere utilizzato per stimare la posizione generale e altri dati tecnici come la velocit\u00e0 di connessione, se avete visitato il sito web\/app in un luogo condiviso e il tipo di dispositivo utilizzato per visitare il sito web\/app. Possono aggregare informazioni sulla nostra pubblicit\u00e0 e su ci\u00f2 che l&#8217;utente vede sul sito web\/app e quindi fornire revisioni, ricerche e rapporti per noi e i nostri inserzionisti. Potremmo inoltre divulgare informazioni personali e non personali sull&#8217;utente a funzionari governativi o delle forze dell&#8217;ordine o a parti private qualora, a nostra esclusiva discrezione, ritenessimo necessario o appropriato rispondere a richieste di risarcimento, procedimenti legali (incluse citazioni in giudizio), proteggere i nostri diritti e interessi o quelli di terzi, la sicurezza del pubblico o di qualsiasi persona, prevenire o interrompere qualsiasi attivit\u00e0 illegale, non etica o legalmente perseguibile, o rispettare in altro modo le ordinanze giudiziarie, le leggi, le norme e i regolamenti applicabili.   <\/p>\n\n<h1 class=\"wp-block-heading\">Dove e quando vengono raccolte le informazioni dai clienti e dagli utenti finali?<\/h1>\n\n<p class=\"wp-block-paragraph\">The GF Recipes raccoglier\u00e0 le informazioni personali che ci invierete. Potremmo anche ricevere informazioni personali su di voi da terzi, come descritto sopra. <\/p>\n\n<h1 class=\"wp-block-heading\">Come utilizziamo il vostro indirizzo e-mail?<\/h1>\n\n<p class=\"wp-block-paragraph\">Inviando il vostro indirizzo e-mail su questo sito\/app, accettate di ricevere e-mail da noi. \u00c8 possibile annullare la partecipazione a uno qualsiasi di questi elenchi di e-mail in qualsiasi momento facendo clic sul link di opt-out o su un&#8217;altra opzione di annullamento dell&#8217;iscrizione inclusa nella rispettiva e-mail. Inviamo e-mail solo a persone che ci hanno autorizzato a contattarle, direttamente o tramite terzi. Non inviamo e-mail commerciali non richieste, perch\u00e9 odiamo lo spam tanto quanto voi. Inviando il vostro indirizzo e-mail, accettate anche di consentirci di utilizzare il vostro indirizzo e-mail per il targeting del pubblico su siti come Facebook, dove mostriamo pubblicit\u00e0 personalizzata a persone specifiche che hanno scelto di ricevere comunicazioni da noi. Gli indirizzi e-mail inviati solo attraverso la pagina di elaborazione dell&#8217;ordine saranno utilizzati al solo scopo di inviare informazioni e aggiornamenti relativi all&#8217;ordine. Tuttavia, se l&#8217;utente ci ha fornito lo stesso indirizzo e-mail attraverso un altro metodo, possiamo utilizzarlo per uno qualsiasi degli scopi indicati nella presente Informativa. Nota: se in qualsiasi momento si desidera annullare l&#8217;iscrizione alla ricezione di future e-mail, includiamo istruzioni dettagliate per l&#8217;annullamento dell&#8217;iscrizione in fondo a ogni e-mail.       <\/p>\n\n<h1 class=\"wp-block-heading\">Per quanto tempo conserviamo le vostre informazioni?<\/h1>\n\n<p class=\"wp-block-paragraph\">Conserviamo le vostre informazioni solo per il tempo necessario a fornirvi The GF Recipes e a soddisfare gli scopi descritti in questa informativa. Questo vale anche per tutti coloro con cui condividiamo le vostre informazioni e che svolgono servizi per nostro conto. Quando non avremo pi\u00f9 bisogno di utilizzare le vostre informazioni e non sar\u00e0 necessario conservarle per adempiere ai nostri obblighi legali o normativi, le rimuoveremo dai nostri sistemi o le spersonalizzeremo in modo da non potervi identificare.  <\/p>\n\n<h1 class=\"wp-block-heading\">Come proteggiamo le vostre informazioni?<\/h1>\n\n<p class=\"wp-block-paragraph\">Implementiamo una serie di misure di sicurezza per preservare la sicurezza dei vostri dati personali quando effettuate un ordine o inserite, inviate o accedete ai vostri dati personali. Offriamo l&#8217;uso di un server sicuro. Tutte le informazioni sensibili\/di credito fornite vengono trasmesse tramite la tecnologia Secure Socket Layer (SSL) e poi crittografate nel database dei nostri fornitori di gateway di pagamento per essere accessibili solo da coloro che sono autorizzati con diritti di accesso speciali a tali sistemi e sono tenuti a mantenere le informazioni riservate. Dopo una transazione, le informazioni private dell&#8217;utente (carte di credito, numeri di previdenza sociale, dati finanziari e cos\u00ec via) non vengono mai conservate in archivio. Tuttavia, non possiamo assicurare o garantire l&#8217;assoluta sicurezza delle informazioni trasmesse a The GF Recipes o garantire che le informazioni dell&#8217;utente sul Servizio non possano essere accessibili, divulgate, alterate o distrutte a causa di una violazione delle nostre protezioni fisiche, tecniche o gestionali.    <\/p>\n\n<h1 class=\"wp-block-heading\">Le mie informazioni possono essere trasferite in altri Paesi?<\/h1>\n\n<p class=\"wp-block-paragraph\">GF Recipes ha sede in Romania. Le informazioni raccolte tramite il nostro sito web, attraverso interazioni dirette con l&#8217;utente o l&#8217;utilizzo dei nostri servizi di assistenza possono essere trasferite di volta in volta ai nostri uffici o al nostro personale, o a terzi, situati in tutto il mondo, e possono essere visualizzate e ospitate in qualsiasi parte del mondo, compresi i paesi che potrebbero non avere leggi di applicabilit\u00e0 generale che regolano l&#8217;uso e il trasferimento di tali dati. Nella misura massima consentita dalla legge applicabile, utilizzando uno qualsiasi dei suddetti servizi, l&#8217;utente acconsente volontariamente al trasferimento transfrontaliero e all&#8217;hosting di tali informazioni.  <\/p>\n\n<h1 class=\"wp-block-heading\">Le informazioni raccolte attraverso il servizio The GF Recipes sono sicure?<\/h1>\n\n<p class=\"wp-block-paragraph\">Prendiamo precauzioni per proteggere la sicurezza delle vostre informazioni. Disponiamo di procedure fisiche, elettroniche e manageriali per salvaguardare, prevenire accessi non autorizzati, mantenere la sicurezza dei dati e utilizzare correttamente le vostre informazioni. Tuttavia, n\u00e9 le persone n\u00e9 i sistemi di sicurezza sono infallibili, compresi i sistemi di crittografia. Inoltre, le persone possono commettere reati intenzionali, commettere errori o non seguire le politiche. Pertanto, pur compiendo sforzi ragionevoli per proteggere le informazioni personali dell&#8217;utente, non possiamo garantirne l&#8217;assoluta sicurezza. Se la legge applicabile impone un obbligo non derogabile di protezione delle informazioni personali, l&#8217;utente accetta che la cattiva condotta intenzionale sar\u00e0 lo standard utilizzato per misurare la nostra conformit\u00e0 a tale obbligo.     <\/p>\n\n<h1 class=\"wp-block-heading\">Posso aggiornare o correggere le mie informazioni?<\/h1>\n\n<p class=\"wp-block-paragraph\">I diritti dell&#8217;utente di richiedere aggiornamenti o correzioni alle informazioni raccolte da The GF Recipes dipendono dal suo rapporto con The GF Recipes. Il personale pu\u00f2 aggiornare o correggere le proprie informazioni come specificato nelle nostre politiche aziendali interne sul lavoro. <\/p>\n\n<p class=\"wp-block-paragraph\">I clienti hanno il diritto di richiedere la restrizione di alcuni usi e divulgazioni di informazioni di identificazione personale come segue. Potete contattarci per (1) aggiornare o correggere le vostre informazioni di identificazione personale, (2) modificare le vostre preferenze in merito alle comunicazioni e alle altre informazioni che ricevete da noi, o (3) cancellare le informazioni di identificazione personale conservate sui nostri sistemi (in base al paragrafo seguente), cancellando il vostro account. Tali aggiornamenti, correzioni, modifiche e cancellazioni non avranno alcun effetto sulle altre informazioni da noi conservate o su quelle fornite a terzi in conformit\u00e0 alla presente Informativa sulla privacy prima di tali aggiornamenti, correzioni, modifiche o cancellazioni. Per proteggere la privacy e la sicurezza dell&#8217;utente, potremmo adottare misure ragionevoli (come la richiesta di una password unica) per verificare l&#8217;identit\u00e0 dell&#8217;utente prima di concedergli l&#8217;accesso al profilo o di effettuare correzioni. L&#8217;utente \u00e8 responsabile del mantenimento della segretezza della propria password unica e delle informazioni relative al proprio account in qualsiasi momento.    <\/p>\n\n<p class=\"wp-block-paragraph\">L&#8217;utente deve essere consapevole che non \u00e8 tecnologicamente possibile rimuovere dal nostro sistema ogni singola registrazione delle informazioni che gli sono state fornite. La necessit\u00e0 di eseguire il backup dei nostri sistemi per proteggere le informazioni da perdite involontarie significa che una copia delle vostre informazioni potrebbe esistere in una forma non cancellabile che sar\u00e0 difficile o impossibile per noi individuare. Subito dopo aver ricevuto la richiesta dell&#8217;utente, tutte le informazioni personali memorizzate nei database che utilizziamo attivamente e in altri supporti facilmente consultabili saranno aggiornate, corrette, modificate o eliminate, a seconda dei casi, non appena e nella misura in cui ci\u00f2 sia ragionevolmente e tecnicamente possibile.  <\/p>\n\n<p class=\"wp-block-paragraph\">Se siete un utente finale e desiderate aggiornare, cancellare o ricevere qualsiasi informazione che vi riguarda, potete farlo contattando l&#8217;organizzazione di cui siete clienti.<\/p>\n\n<h1 class=\"wp-block-heading\">Personale<\/h1>\n\n<p class=\"wp-block-paragraph\">Se siete lavoratori o candidati di The GF Recipes, raccogliamo le informazioni che ci fornite volontariamente. Utilizziamo le informazioni raccolte per scopi legati alle risorse umane, al fine di gestire i benefici per i lavoratori e di esaminare i candidati. <\/p>\n\n<p class=\"wp-block-paragraph\">Potete contattarci per (1) aggiornare o correggere le vostre informazioni, (2) modificare le vostre preferenze in merito alle comunicazioni e alle altre informazioni che ricevete da noi, o (3) ricevere una registrazione delle informazioni che vi riguardano in nostro possesso. Tali aggiornamenti, correzioni, modifiche e cancellazioni non avranno alcun effetto sulle altre informazioni da noi conservate o su quelle fornite a terzi in conformit\u00e0 alla presente Informativa sulla privacy prima di tali aggiornamenti, correzioni, modifiche o cancellazioni. <\/p>\n\n<h1 class=\"wp-block-heading\">Vendita di un&#8217;attivit\u00e0 commerciale<\/h1>\n\n<p class=\"wp-block-paragraph\">Ci riserviamo il diritto di trasferire le informazioni a terzi in caso di vendita, fusione o altro trasferimento di tutti o sostanzialmente tutti i beni di The GF Recipes o di una delle sue Corporate Affiliate (come definite nel presente documento), o di quella parte di The GF Recipes o di una delle sue Corporate Affiliate a cui si riferisce il Servizio, o nel caso in cui interrompiamo la nostra attivit\u00e0 o presentiamo un&#8217;istanza o abbiamo presentato contro di noi un&#8217;istanza di fallimento, riorganizzazione o procedimento simile, a condizione che la terza parte accetti di aderire ai termini della presente Informativa sulla privacy.<\/p>\n\n<h1 class=\"wp-block-heading\">Affiliati<\/h1>\n\n<p class=\"wp-block-paragraph\">Potremmo divulgare le informazioni (comprese quelle personali) che vi riguardano alle nostre Affiliate aziendali. Ai fini della presente Informativa sulla privacy, per &#8220;Affiliato aziendale&#8221; si intende qualsiasi persona o entit\u00e0 che direttamente o indirettamente controlla, \u00e8 controllata da o \u00e8 sotto controllo comune con The GF Recipes, sia per propriet\u00e0 che per altro. Tutte le informazioni relative all&#8217;utente che forniamo alle nostre societ\u00e0 affiliate saranno trattate da tali societ\u00e0 affiliate in conformit\u00e0 con i termini della presente Informativa sulla privacy.  <\/p>\n\n<h1 class=\"wp-block-heading\">Legge applicabile<\/h1>\n\n<p class=\"wp-block-paragraph\">La presente Informativa sulla privacy \u00e8 disciplinata dalle leggi della Romania, senza tener conto delle disposizioni sul conflitto di leggi. L&#8217;utente acconsente alla giurisdizione esclusiva dei tribunali in relazione a qualsiasi azione o controversia che dovesse insorgere tra le parti ai sensi della presente Informativa sulla privacy o in relazione ad essa, fatta eccezione per gli individui che potrebbero avere il diritto di presentare reclami ai sensi del Privacy Shield o del quadro normativo svizzero-americano. <\/p>\n\n<p class=\"wp-block-paragraph\">Il presente Accordo e l&#8217;utilizzo del sito web\/app da parte dell&#8217;utente sono disciplinati dalle leggi della Romania, ad esclusione delle norme sui conflitti di legge. L&#8217;utilizzo del sito web\/app da parte dell&#8217;utente pu\u00f2 essere soggetto anche ad altre leggi locali, statali, nazionali o internazionali. <\/p>\n\n<p class=\"wp-block-paragraph\">Utilizzando The GF Recipes o contattandoci direttamente, accettate la presente Informativa sulla privacy. Se non accettate la presente Informativa sulla privacy, non dovreste utilizzare il nostro sito web o i nostri servizi. L&#8217;uso continuato del sito web, l&#8217;impegno diretto con noi o la pubblicazione di modifiche alla presente Informativa sulla privacy che non influiscono in modo significativo sull&#8217;uso o sulla divulgazione dei vostri dati personali implicheranno l&#8217;accettazione di tali modifiche.  <\/p>\n\n<h1 class=\"wp-block-heading\">Il vostro consenso<\/h1>\n\n<p class=\"wp-block-paragraph\">Abbiamo aggiornato la nostra Informativa sulla privacy per fornirvi una trasparenza completa su ci\u00f2 che viene impostato quando visitate il nostro sito e su come viene utilizzato. Utilizzando il nostro sito\/app, registrando un account o effettuando un acquisto, l&#8217;utente acconsente alla nostra Informativa sulla privacy e ne accetta i termini. <\/p>\n\n<h1 class=\"wp-block-heading\">Link ad altri siti web<\/h1>\n\n<p class=\"wp-block-paragraph\">La presente Informativa sulla privacy si applica solo ai Servizi. I Servizi possono contenere link ad altri siti web non gestiti o controllati da The GF Recipes. Non siamo responsabili del contenuto, dell&#8217;accuratezza o delle opinioni espresse in tali siti web, e tali siti non sono da noi indagati, monitorati o controllati per quanto riguarda l&#8217;accuratezza o la completezza. Si ricorda che quando si utilizza un link per passare dai Servizi a un altro sito web, la nostra Informativa sulla privacy non \u00e8 pi\u00f9 in vigore. La navigazione e l&#8217;interazione dell&#8217;utente su qualsiasi altro sito web, compresi quelli che hanno un link sulla nostra piattaforma, \u00e8 soggetta alle regole e alle politiche di quel sito web. Tali terze parti possono utilizzare i propri cookie o altri metodi per raccogliere informazioni sull&#8217;utente.     <\/p>\n\n<h1 class=\"wp-block-heading\">Pubblicit\u00e0<\/h1>\n\n<p class=\"wp-block-paragraph\">Questo sito\/app pu\u00f2 contenere pubblicit\u00e0 di terzi e link a siti di terzi. GF Recipes non rilascia alcuna dichiarazione in merito all&#8217;accuratezza o all&#8217;idoneit\u00e0 delle informazioni contenute in tali annunci o siti e non si assume alcuna responsabilit\u00e0 per la condotta o il contenuto di tali annunci e siti e per le offerte fatte da terzi. <\/p>\n\n<p class=\"wp-block-paragraph\">La pubblicit\u00e0 mantiene The GF Recipes e molti dei siti e servizi che utilizzate gratuitamente. Lavoriamo duramente per assicurarci che gli annunci siano sicuri, non invadenti e il pi\u00f9 possibile pertinenti. <\/p>\n\n<p class=\"wp-block-paragraph\">Gli annunci pubblicitari di terzi e i link ad altri siti in cui vengono pubblicizzati beni o servizi non costituiscono un&#8217;approvazione o una raccomandazione da parte di The GF Recipes dei siti, dei beni o dei servizi di terzi. The GF Recipes non si assume alcuna responsabilit\u00e0 per il contenuto degli annunci, le promesse fatte o la qualit\u00e0\/affidabilit\u00e0 dei prodotti o servizi offerti in tutti gli annunci. <\/p>\n\n<h1 class=\"wp-block-heading\">Cookie per la pubblicit\u00e0<\/h1>\n\n<p class=\"wp-block-paragraph\">Questi cookie raccolgono nel tempo informazioni sulla vostra attivit\u00e0 online sul sito\/app e su altri servizi online per rendere gli annunci pubblicitari online pi\u00f9 pertinenti ed efficaci per voi. Si tratta della cosiddetta pubblicit\u00e0 basata sugli interessi. Svolgono anche funzioni come evitare che lo stesso annuncio ricompaia continuamente e garantire la corretta visualizzazione degli annunci per gli inserzionisti. Senza i cookie, \u00e8 molto difficile per un inserzionista raggiungere il proprio pubblico o sapere quanti annunci sono stati mostrati e quanti clic hanno ricevuto.   <\/p>\n\n<h1 class=\"wp-block-heading\">Biscotti<\/h1>\n\n<p class=\"wp-block-paragraph\">The GF Recipes utilizza &#8220;Cookie&#8221; per identificare le aree del nostro sito web che hai visitato. Un Cookie \u00e8 un piccolo pezzo di dati memorizzato sul tuo computer o dispositivo mobile dal tuo browser web. Utilizziamo i Cookie per migliorare le prestazioni e la funzionalit\u00e0 del nostro sito web\/app, ma non sono essenziali per il loro utilizzo. Tuttavia, senza questi cookie, alcune funzionalit\u00e0 come i video potrebbero diventare non disponibili o ti sarebbe richiesto di inserire i tuoi dettagli di accesso ogni volta che visiti il sito web\/app poich\u00e9 non saremmo in grado di ricordare che avevi effettuato l&#8217;accesso in precedenza. La maggior parte dei browser web pu\u00f2 essere impostata per disabilitare l&#8217;uso dei Cookie. Tuttavia, se disabiliti i Cookie, potresti non essere in grado di accedere correttamente o affatto alla funzionalit\u00e0 del nostro sito web. Non inseriamo mai informazioni personali identificabili nei Cookie.      <\/p>\n\n<h1 class=\"wp-block-heading\">Bloccare e disabilitare i cookie e tecnologie simili<\/h1>\n\n<p class=\"wp-block-paragraph\">Ovunque vi troviate, potete anche impostare il vostro browser in modo da bloccare i cookie e tecnologie simili, ma questa azione potrebbe bloccare i nostri cookie essenziali e impedire al nostro sito web di funzionare correttamente, e potreste non essere in grado di utilizzare appieno tutte le sue caratteristiche e i suoi servizi. L&#8217;utente deve inoltre essere consapevole del fatto che potrebbe perdere alcune informazioni salvate (ad esempio, i dati di accesso salvati, le preferenze del sito) se blocca i cookie sul proprio browser. I diversi browser mettono a disposizione controlli diversi. La disabilitazione di un cookie o di una categoria di cookie non comporta la cancellazione del cookie dal browser; per ulteriori informazioni \u00e8 necessario consultare il menu di aiuto del browser.   <\/p>\n\n<h1 class=\"wp-block-heading\">Servizi di Remarketing<\/h1>\n\n<p class=\"wp-block-paragraph\">Utilizziamo servizi di remarketing. Che cos&#8217;\u00e8 il remarketing? Nel marketing digitale, il remarketing (o retargeting) \u00e8 la pratica di proporre annunci su Internet a persone che hanno gi\u00e0 visitato il vostro sito web. In questo modo la vostra azienda pu\u00f2 sembrare che &#8220;segua&#8221; le persone su Internet, proponendo annunci sui siti e sulle piattaforme che utilizzano maggiormente.   <\/p>\n\n<h1 class=\"wp-block-heading\">Privacy dei bambini<\/h1>\n\n<p class=\"wp-block-paragraph\">Raccogliamo informazioni da bambini di et\u00e0 inferiore ai 13 anni solo per migliorare i nostri servizi. Se siete un genitore o un tutore e siete a conoscenza del fatto che vostro figlio ci ha fornito dati personali senza il vostro consenso, vi preghiamo di contattarci. Se veniamo a conoscenza di aver raccolto dati personali da persone di et\u00e0 inferiore ai 13 anni senza aver verificato il consenso dei genitori, ci attiviamo per rimuovere tali informazioni dai nostri server.  <\/p>\n\n<h1 class=\"wp-block-heading\">Modifiche alla nostra politica sulla privacy<\/h1>\n\n<p class=\"wp-block-paragraph\">Potremmo cambiare il nostro Servizio e le nostre politiche e potremmo dover apportare modifiche alla presente Informativa sulla privacy in modo che rifletta accuratamente il nostro Servizio e le nostre politiche. Se non diversamente richiesto dalla legge, vi informeremo (ad esempio, attraverso il nostro Servizio) prima di apportare modifiche alla presente Informativa sulla privacy e vi daremo l&#8217;opportunit\u00e0 di esaminarle prima che entrino in vigore. In seguito, se continuerete a utilizzare il Servizio, sarete vincolati dall&#8217;Informativa sulla privacy aggiornata. Se l&#8217;utente non vuole accettare questa o qualsiasi altra Informativa sulla privacy aggiornata, pu\u00f2 cancellare il proprio account.   <\/p>\n\n<h1 class=\"wp-block-heading\">Servizi di terze parti<\/h1>\n\n<p class=\"wp-block-paragraph\">Potremmo visualizzare, includere o mettere a disposizione contenuti di terze parti (tra cui dati, informazioni, applicazioni e altri prodotti\/servizi) o fornire collegamenti a siti web o servizi di terze parti (&#8220;Servizi di Terze Parti&#8221;).<\/p>\n\n<p class=\"wp-block-paragraph\">Riconosci e accetti che The GF Recipes non sar\u00e0 responsabile per alcun Servizio di Terze Parti, compresa la loro accuratezza, completezza, tempestivit\u00e0, validit\u00e0, conformit\u00e0 al copyright, legalit\u00e0, decenza, qualit\u00e0 o qualsiasi altro aspetto correlato. The GF Recipes non assume e non avr\u00e0 alcuna responsabilit\u00e0 nei tuoi confronti o nei confronti di qualsiasi altra persona o entit\u00e0 per quanto riguarda i Servizi di Terze Parti. <\/p>\n\n<p class=\"wp-block-paragraph\">I Servizi di Terze Parti e i collegamenti ad essi sono forniti esclusivamente come comodit\u00e0 per te e tu accedi e li utilizzi completamente a tuo rischio e soggetto ai termini e alle condizioni di tali terze parti.<\/p>\n\n<h1 class=\"wp-block-heading\">Pixel di Facebook<\/h1>\n\n<p class=\"wp-block-paragraph\">Il pixel di Facebook \u00e8 uno strumento di analisi che vi permette di misurare l&#8217;efficacia della vostra pubblicit\u00e0 comprendendo le azioni che le persone compiono sul vostro sito web. Il pixel pu\u00f2 essere utilizzato per: Assicurarsi che i vostri annunci vengano mostrati alle persone giuste. Il pixel di Facebook pu\u00f2 raccogliere informazioni dal vostro dispositivo quando utilizzate il servizio. Il pixel di Facebook raccoglie informazioni che vengono conservate in conformit\u00e0 con la sua Informativa sulla privacy.   <\/p>\n\n<h1 class=\"wp-block-heading\">Come gestiamo i tuoi social login?<\/h1>\n\n<p class=\"wp-block-paragraph\">In breve: se decidi di registrarti o di accedere ai nostri Servizi utilizzando un account di social media, potremmo avere accesso a informazioni di ceftain su di te.<br\/><br\/>I nostri Servizi ti offrono la possibilit\u00e0 di registrarti e accedere utilizzando i dati del tuo account di social media di terze parti (come i tuoi login Google o Apple). Se scegli di farlo, riceveremo<br\/>alcune informazioni sul tuo profilo dal tuo provider di social media. Le informazioni sul profilo che riceviamo possono variare a seconda del provider di social media in questione, ma spesso includono<br\/>il tuo nome, il tuo indirizzo e-mail, la tua lista di amici e la tua immagine del profilo, oltre ad altre informazioni che scegli di rendere pubbliche su tale piattaforma di social media.  <br\/><br\/>Utilizzeremo le informazioni ricevute solo per gli scopi descritti nella presente informativa sulla privacy o altrimenti indicati all&#8217;utente nei Servizi in questione. Si prega di notare che<br\/>non controlla e non \u00e8 responsabile di altri usi dei tuoi dati personali da parte del tuo provider di social media di terze parti. Ti consigliamo di consultare la loro informativa sulla privacy per<br\/>capire come raccolgono, utilizzano e condividono i tuoi dati personali e come puoi impostare le tue preferenze sulla privacy nei loro siti e applicazioni.  <\/p>\n\n<h1 class=\"wp-block-heading\">Tecnologie di tracciamento<\/h1>\n\n<ul class=\"wp-block-list\">\n<li>Google Maps API &#8211; Un solido strumento che pu\u00f2 essere utilizzato per creare una mappa personalizzata, una mappa ricercabile, funzioni di check-in, visualizzare dati in tempo reale sincronizzati con la posizione, pianificare percorsi o creare un mashup, solo per citarne alcuni.Google Maps API pu\u00f2 raccogliere informazioni dall&#8217;utente e dal suo dispositivo per motivi di sicurezza.Google Maps API raccoglie informazioni che vengono conservate in conformit\u00e0 con la sua Informativa sulla privacy.<br\/><\/li>\n\n\n\n<li>L&#8217;archiviazione locale &#8211; talvolta nota come archiviazione DOM &#8211; fornisce alle applicazioni web metodi e protocolli per l&#8217;archiviazione dei dati lato client. L&#8217;archiviazione web supporta l&#8217;archiviazione persistente dei dati, simile ai cookie, ma con una capacit\u00e0 notevolmente migliorata e senza informazioni memorizzate nell&#8217;intestazione della richiesta HTTP. <br\/><\/li>\n\n\n\n<li>Sessioni &#8211; $elnombre utilizza le &#8220;sessioni&#8221; per identificare le aree del nostro sito web che hai visitato. Una sessione \u00e8 una piccola porzione di dati memorizzata sul tuo computer o dispositivo mobile dal tuo browser web. <\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Informazioni sul Regolamento generale sulla protezione dei dati (GDPR)<\/h1>\n\n<p class=\"wp-block-paragraph\">In questa sezione della nostra Informativa sulla privacy spiegheremo esattamente come e perch\u00e9 vengono raccolti questi dati e come li proteggiamo per evitare che vengano replicati o utilizzati in modo errato.<\/p>\n\n<h1 class=\"wp-block-heading\">Che cos&#8217;\u00e8 il GDPR?<\/h1>\n\n<p class=\"wp-block-paragraph\">Il GDPR \u00e8 una legge sulla privacy e sulla protezione dei dati a livello europeo che regolamenta le modalit\u00e0 di protezione dei dati dei residenti nell&#8217;UE da parte delle aziende e migliora il controllo che i residenti nell&#8217;UE hanno sui loro dati personali.<\/p>\n\n<p class=\"wp-block-paragraph\">Il GDPR \u00e8 rilevante per qualsiasi azienda che opera a livello globale e non solo per le aziende con sede nell&#8217;UE e per i residenti nell&#8217;UE. I dati dei nostri clienti sono importanti indipendentemente dalla loro ubicazione, ed \u00e8 per questo che abbiamo implementato i controlli del GDPR come standard di base per tutte le nostre operazioni in tutto il mondo. <\/p>\n\n<h1 class=\"wp-block-heading\">Cosa sono i dati personali?<\/h1>\n\n<p class=\"wp-block-paragraph\">Qualsiasi dato che si riferisce a un individuo identificabile o identificato. Il GDPR copre un ampio spettro di informazioni che potrebbero essere utilizzate da sole, o in combinazione con altre informazioni, per identificare una persona. I dati personali vanno oltre il nome o l&#8217;indirizzo e-mail di una persona. Alcuni esempi includono informazioni finanziarie, opinioni politiche, dati genetici, dati biometrici, indirizzi IP, indirizzi fisici, orientamento sessuale ed etnia.   <\/p>\n\n<p class=\"wp-block-paragraph\">I principi di protezione dei dati includono requisiti quali:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>I dati personali raccolti devono essere trattati in modo equo, legale e trasparente e devono essere utilizzati solo in un modo che una persona si aspetterebbe ragionevolmente:<\/li>\n\n\n\n<li>I dati personali devono essere raccolti solo per soddisfare uno scopo specifico e devono essere utilizzati solo per tale scopo. Le organizzazioni devono specificare il motivo per cui hanno bisogno dei dati personali quando li raccolgono. <\/li>\n\n\n\n<li>I dati personali non devono essere conservati pi\u00f9 a lungo di quanto sia necessario per raggiungere il loro scopo.<\/li>\n\n\n\n<li>Le persone interessate dal GDPR hanno il diritto di accedere ai propri dati personali. Possono inoltre richiedere una copia dei propri dati e che questi vengano aggiornati, cancellati, limitati o trasferiti a un&#8217;altra organizzazione. <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Se ti trovi nell&#8217;UE o nel Regno Unito, questa sezione si applica a te.<\/p>\n\n<p class=\"wp-block-paragraph\">Il Regolamento generale sulla protezione dei dati (GDPR) e il GDPR del Regno Unito ci impongono di spiegare quali sono le basi giuridiche valide su cui ci basiamo per trattare i tuoi dati personali. Per questo motivo: possiamo affidarci a<br\/>le seguenti basi legali per trattare i tuoi dati personali. <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Consenso. Possiamo trattare i tuoi dati se ci hai dato il permesso (cio\u00e8 il consenso) di utilizzare i tuoi dati personali per uno scopo specifico. Puoi ritirare il tuo consenso su<br\/>in qualsiasi momento. Per saperne di pi\u00f9 sulla revoca del consenso_   <\/li>\n\n\n\n<li>Interessi legittimi. Possiamo trattare le tue informazioni quando riteniamo che sia ragionevolmente necessario per raggiungere i nostri legittimi interessi commerciali e tali interessi non prevalgono su<br\/>i tuoi interessi e i tuoi diritti e libert\u00e0 fondamentali. Ad esempio, possiamo trattare i tuoi dati personali per alcune delle finalit\u00e0 descritte al fine di:  <\/li>\n\n\n\n<li>Sviluppare e mostrare contenuti pubblicitari personalizzati e pertinenti per i nostri utenti<\/li>\n\n\n\n<li>Obblighi legali. Potremmo trattare i tuoi dati qualora ritenessimo che ci\u00f2 sia necessario per adempiere ai nostri obblighi legali, come ad esempio per collaborare con le forze dell&#8217;ordine o con l&#8217;agenzia di regolamentazione<br\/>, per esercitare o difendere i nostri diritti legali o per divulgare i tuoi dati come prova in una controversia in cui siamo coinvolti. <\/li>\n\n\n\n<li>Interessi vitali. Potremmo trattare le tue informazioni qualora ritenessimo necessario proteggere i tuoi interessi vitali o gli interessi vitali di una terza parte, come ad esempio situazioni che coinvolgono<br\/>potenziali minacce alla sicurezza di qualsiasi persona. <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Se ti trovi in Canada, questa sezione si applica a te.<br\/><br\/>Possiamo trattare le tue informazioni se ci hai dato il permesso specifico (cio\u00e8 il consenso esplicito) di utilizzare le tue informazioni personali per uno scopo specifico, o in situazioni in cui il tuo consenso<br\/>pu\u00f2 essere dedotto (cio\u00e8 il consenso implicito). Puoi ritirare il tuo consenso in qualsiasi momento.<br\/>In alcuni casi eccezionali, la legge ci consente di trattare i tuoi dati senza il tuo consenso, ad esempio: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Se la raccolta \u00e8 chiaramente nell&#8217;interesse di un individuo e il consenso non pu\u00f2 essere ottenuto in modo tempestivo<\/li>\n\n\n\n<li>Per le indagini e l&#8217;individuazione e la prevenzione delle frodi<\/li>\n\n\n\n<li>Per le transazioni commerciali, a condizione che siano soddisfatte determinate condizioni<\/li>\n\n\n\n<li>Se \u00e8 contenuta in una dichiarazione di un testimone e la raccolta \u00e8 necessaria per valutare, elaborare o liquidare una richiesta di risarcimento assicurativo<\/li>\n\n\n\n<li>Per identificare persone ferite, malate o decedute e comunicare con i parenti pi\u00f9 stretti<\/li>\n\n\n\n<li>Se abbiamo ragionevoli motivi per ritenere che una persona sia stata, sia o possa essere vittima di un abuso finanziario<\/li>\n\n\n\n<li>Se \u00e8 ragionevole aspettarsi che la raccolta e l&#8217;utilizzo con il consenso compromettano la disponibilit\u00e0 o l&#8217;accuratezza delle informazioni e se la raccolta \u00e8 ragionevole per scopi legati<br\/>all&#8217;investigazione di una violazione di un accordo o di un&#8217;infrazione delle leggi del Canada o di una provincia.<\/li>\n\n\n\n<li>Se la divulgazione \u00e8 richiesta per ottemperare a una citazione, a un mandato, a un ordine del tribunale o alle regole del tribunale relative alla produzione di documenti.<\/li>\n\n\n\n<li>Se le informazioni sono state prodotte da un individuo nel corso del suo impiego, della sua attivit\u00e0 o della sua professione e la raccolta \u00e8 coerente con gli scopi per cui le informazioni sono state prodotte<\/li>\n\n\n\n<li>Se la raccolta ha finalit\u00e0 esclusivamente giornalistiche, artistiche o letterarie<\/li>\n\n\n\n<li>Se le informazioni sono disponibili al pubblico e sono specificate dai regolamenti<\/li>\n<\/ul>\n\n<h1 class=\"wp-block-heading\">Perch\u00e9 il GDPR \u00e8 importante?<\/h1>\n\n<p class=\"wp-block-paragraph\">Il GDPR aggiunge alcuni nuovi requisiti in merito a come le aziende devono proteggere i dati personali degli individui che raccolgono ed elaborano. Inoltre, alza la posta in gioco per la conformit\u00e0 aumentando l&#8217;applicazione e imponendo multe pi\u00f9 salate in caso di violazione. Al di l\u00e0 di questi fatti, \u00e8 semplicemente la cosa giusta da fare. Noi di The GF Recipes crediamo fermamente che la privacy dei vostri dati sia molto importante e abbiamo gi\u00e0 messo in atto solide pratiche di sicurezza e privacy che vanno oltre i requisiti di questa nuova normativa.   <\/p>\n\n<h1 class=\"wp-block-heading\">Diritti dell&#8217;interessato &#8211; Accesso, portabilit\u00e0 e cancellazione dei dati<\/h1>\n\n<p class=\"wp-block-paragraph\">Ci impegniamo ad aiutare i nostri clienti a soddisfare i requisiti del GDPR in materia di diritti degli interessati. GF Recipes elabora o memorizza tutti i dati personali presso fornitori pienamente verificati e conformi alla DPA. Conserviamo tutte le conversazioni e i dati personali per un massimo di 6 anni, a meno che il vostro account non venga cancellato. In tal caso, smaltiremo tutti i dati in conformit\u00e0 ai nostri Termini di servizio e alla nostra Informativa sulla privacy, ma non li conserveremo per pi\u00f9 di 60 giorni.   <\/p>\n\n<p class=\"wp-block-paragraph\">Siamo consapevoli che se lavorate con clienti dell&#8217;UE, dovete essere in grado di fornire loro la possibilit\u00e0 di accedere, aggiornare, recuperare e rimuovere i dati personali. Vi abbiamo fregati! Siamo stati impostati come self-service fin dall&#8217;inizio e vi abbiamo sempre dato accesso ai vostri dati e a quelli dei vostri clienti. Il nostro team di assistenza clienti \u00e8 a vostra disposizione per rispondere a qualsiasi domanda sul funzionamento dell&#8217;API.   <\/p>\n\n<h1 class=\"wp-block-heading\">Residenti in California<\/h1>\n\n<p class=\"wp-block-paragraph\">La legge sulla privacy dei consumatori della California (CCPA) ci impone di divulgare le categorie di informazioni personali che raccogliamo e il modo in cui le utilizziamo, le categorie di fonti da cui raccogliamo le informazioni personali e le terze parti con cui le condividiamo, come abbiamo spiegato sopra.<\/p>\n\n<p class=\"wp-block-paragraph\">Siamo inoltre tenuti a comunicare informazioni sui diritti di cui godono i residenti in California ai sensi della legge californiana. L&#8217;utente pu\u00f2 esercitare i seguenti diritti: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Diritto di sapere e di accesso. L&#8217;utente pu\u00f2 presentare una richiesta verificabile di informazioni relative a: (1) categorie di informazioni personali che raccogliamo, utilizziamo o condividiamo; (2) scopi per i quali le categorie di informazioni personali vengono raccolte o utilizzate da noi; (3) categorie di fonti da cui raccogliamo le informazioni personali; e (4) specifiche informazioni personali che abbiamo raccolto su di voi. <\/li>\n\n\n\n<li>Diritto alla parit\u00e0 di servizio. Non vi discrimineremo se esercitate il vostro diritto alla privacy. <\/li>\n\n\n\n<li>Diritto di cancellazione. L&#8217;utente pu\u00f2 presentare una richiesta verificabile di chiusura del proprio account e noi cancelleremo le Informazioni personali sull&#8217;utente raccolte. <\/li>\n\n\n\n<li>Richiedere che un&#8217;azienda che vende i dati personali di un consumatore non venda i dati personali del consumatore.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">In caso di richiesta, abbiamo un mese di tempo per rispondere. Se desiderate esercitare uno di questi diritti, contattateci. <\/p>\n\n<p class=\"wp-block-paragraph\">Non vendiamo le informazioni personali dei nostri utenti.<\/p>\n\n<p class=\"wp-block-paragraph\">Per ulteriori informazioni su questi diritti, contattateci.<\/p>\n\n<h1 class=\"wp-block-heading\">Legge sulla protezione della privacy online in California (CalOPPA)<\/h1>\n\n<p class=\"wp-block-paragraph\">Il CalOPPA ci impone di divulgare le categorie di informazioni personali che raccogliamo e il modo in cui le utilizziamo, le categorie di fonti da cui raccogliamo le informazioni personali e le terze parti con cui le condividiamo, come abbiamo spiegato sopra.<\/p>\n\n<p class=\"wp-block-paragraph\">Gli utenti di CalOPPA hanno i seguenti diritti:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Diritto di sapere e di accesso. L&#8217;utente pu\u00f2 presentare una richiesta verificabile di informazioni relative a: (1) categorie di informazioni personali che raccogliamo, utilizziamo o condividiamo; (2) scopi per i quali le categorie di informazioni personali vengono raccolte o utilizzate da noi; (3) categorie di fonti da cui raccogliamo le informazioni personali; e (4) specifiche informazioni personali che abbiamo raccolto su di voi. <\/li>\n\n\n\n<li>Diritto alla parit\u00e0 di servizio. Non vi discrimineremo se esercitate il vostro diritto alla privacy. <\/li>\n\n\n\n<li>Diritto di cancellazione. L&#8217;utente pu\u00f2 presentare una richiesta verificabile di chiusura del proprio account e noi cancelleremo le Informazioni personali sull&#8217;utente raccolte. <\/li>\n\n\n\n<li>Diritto di richiedere che un&#8217;azienda che vende i dati personali di un consumatore non li venda.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">In caso di richiesta, abbiamo un mese di tempo per rispondere. Se desiderate esercitare uno di questi diritti, contattateci. <\/p>\n\n<p class=\"wp-block-paragraph\">Non vendiamo le informazioni personali dei nostri utenti.<\/p>\n\n<p class=\"wp-block-paragraph\">Per ulteriori informazioni su questi diritti, contattateci.<\/p>\n\n<h1 class=\"wp-block-heading\">Contatto<\/h1>\n\n<p class=\"wp-block-paragraph\">Non esitate a contattarci per qualsiasi domanda.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Via e-mail: <a href=\"mailto:radu@thegfrecipes.com\">radu@thegfrecipes.com<\/a><\/li>\n\n\n\n<li>Tramite questo link: <a href=\"https:\/\/www.thegfrecipes.com\/contact\/\">https:\/\/www.thegfrecipes.com\/it\/contatta-thegfrecipes\/<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aggiornato al 2024-08-14 The GF Recipes (&#8220;noi&#8221;, &#8220;nostro&#8221; o &#8220;ci&#8221;) si impegna a proteggere la vostra privacy. La presente Informativa sulla privacy spiega come i vostri dati personali vengono raccolti, utilizzati e divulgati da The GF Recipes. Questa Informativa sulla Privacy si applica al nostro sito web e ai suoi sottodomini associati (collettivamente, il nostro&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.thegfrecipes.com\/it\/informativa-sulla-privacy\">Leggi di pi\u00f9<\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-119930","page","type-page","status-publish","hentry"],"acf":{"sub_title":"","show_featured_recipes_slider":false,"featured_recipes":null,"featured_recipes_background_image":null,"featured_recipes_layout_type":"mixed","make_featured_recipes_fixed_width":false,"background_image":null,"background_image_size":"default","parallax_background":"default","enable_custom_header_settings":false,"top_menu_type":"version_1","logo_image":null,"logo_image_width":210},"default_slug":"privacy-policy","_links":{"self":[{"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/pages\/119930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/comments?post=119930"}],"version-history":[{"count":6,"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/pages\/119930\/revisions"}],"predecessor-version":[{"id":131092,"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/pages\/119930\/revisions\/131092"}],"wp:attachment":[{"href":"https:\/\/www.thegfrecipes.com\/it\/wp-json\/wp\/v2\/media?parent=119930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}