{"id":119783,"date":"2023-03-05T21:19:23","date_gmt":"2023-03-05T19:19:23","guid":{"rendered":"https:\/\/www.thegfrecipes.com\/recipe\/glutenfreie-ricotta-gnocchi\/"},"modified":"2023-08-04T11:42:56","modified_gmt":"2023-08-04T09:42:56","slug":"glutenfreie-ricotta-gnocchi","status":"publish","type":"osetin_recipe","link":"https:\/\/www.thegfrecipes.com\/de\/rezept\/glutenfreie-ricotta-gnocchi","title":{"rendered":"Gnocchi"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\">F\u00fcr dieses Rezept f\u00fcr glutenfreie Ricotta-Gnocchi ben\u00f6tigen Sie die folgenden Zutaten:<\/h4>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-1024x469.jpg\" alt=\"\" class=\"wp-image-49985\" srcset=\"https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-1024x469.jpg 1024w, https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-300x138.jpg 300w, https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-768x352.jpg 768w, https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-1536x704.jpg 1536w, https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-2048x939.jpg 2048w, https:\/\/www.thegfrecipes.com\/wp-content\/uploads\/2023\/03\/IMG_20210127_215525-500x229.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Gnocchi werden aus einer Mischung aus Kartoffelp\u00fcree, frischen Erbsen und Mehl hergestellt und sind leicht, fluffig und voller Geschmack. Mit einer pikanten Sauce und geriebenem Parmesank\u00e4se \u00fcberbacken, sind sie die perfekte Kombination aus reichhaltig und s\u00e4ttigend. <\/p>\n","protected":false},"author":2,"featured_media":116151,"comment_status":"open","ping_status":"closed","template":"","format":"standard","categories":[1635],"recipe_feature":[1614],"recipe_ingredient":[1372,1427,1513,1435,1358,1549,1442,1433,1509,1514,1536,1541,1343,1357,1480],"recipe_cuisine":[1613],"class_list":["post-119783","osetin_recipe","type-osetin_recipe","status-publish","format-standard","has-post-thumbnail","hentry","category-abendessen","recipe_feature-glutenfrei","recipe_ingredient-butter-de","recipe_ingredient-ei","recipe_ingredient-erbsen","recipe_ingredient-fein-gehackter-dill","recipe_ingredient-gebackene-kartoffeln","recipe_ingredient-geschabter-parmesan","recipe_ingredient-knoblauchzehen-de","recipe_ingredient-natives-olivenoel-extra","recipe_ingredient-paprikapulver","recipe_ingredient-pfeffer","recipe_ingredient-ricotta-kase","recipe_ingredient-salz","recipe_ingredient-schar-universal-mix-de-2","recipe_ingredient-speckscheiben","recipe_ingredient-zitronenschale","recipe_cuisine-italien"],"acf":{"sub_title":"","acf_featured_image":null,"recipe_category":[1635],"recipe_cuisine":[1613],"recipe_features":[1614],"layout_type_for_single_recipe":"default","custom_image_for_header":null,"recipe_details_position":"default","quick_description":"Unsere Gnocchi werden aus einer Mischung aus Kartoffelp\u00fcree, frischen Erbsen und Mehl hergestellt und sind leicht, fluffig und voller Geschmack. Mit einer pikanten Sauce und geriebenem Parmesank\u00e4se \u00fcberbacken, sind sie die perfekte Kombination aus reichhaltig und s\u00e4ttigend. \n\n","recipe_serves":"4","recipe_difficulty":"1","recipe_preparation_time":"15 min","recipe_just_cooking_time":"20 min","recipe_cooking_time":"35 min","recipe_cooking_temperature":"","searchable_ingredients":true,"ingredients":[{"ingredient_obj":277,"ingredient_name":"Gnocchi","ingredient_amount":"2 ","ingredient_note":"","separator":true,"custom_link":""},{"ingredient_obj":277,"ingredient_name":"","ingredient_amount":"2 ","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":125,"ingredient_name":"","ingredient_amount":"1 Essl\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":43,"ingredient_name":"","ingredient_amount":"1 Teel\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":182,"ingredient_name":"","ingredient_amount":"1 Teel\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":240,"ingredient_name":"","ingredient_amount":"100 g","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":52,"ingredient_name":"Topping","ingredient_amount":"1","ingredient_note":"besiegt","separator":false,"custom_link":""},{"ingredient_obj":55,"ingredient_name":"Restliche Zutaten","ingredient_amount":"1 Essl\u00f6ffel","ingredient_note":"","separator":true,"custom_link":""},{"ingredient_obj":55,"ingredient_name":"","ingredient_amount":"1 Essl\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":274,"ingredient_name":"","ingredient_amount":"1\/2 Teel\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":59,"ingredient_name":"","ingredient_amount":"4","ingredient_note":"Gehacktes","separator":false,"custom_link":""},{"ingredient_obj":279,"ingredient_name":"","ingredient_amount":"1","ingredient_note":"Gehacktes","separator":false,"custom_link":""},{"ingredient_obj":53,"ingredient_name":"","ingredient_amount":"50 g","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":244,"ingredient_name":"","ingredient_amount":"100 g","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":280,"ingredient_name":"","ingredient_amount":"100 g","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":159,"ingredient_name":"","ingredient_amount":"1 Teel\u00f6ffel","ingredient_note":"","separator":false,"custom_link":""},{"ingredient_obj":164,"ingredient_name":"","ingredient_amount":"50 g","ingredient_note":"","separator":false,"custom_link":""}],"steps":[{"step_title":"","step_duration":"","step_description":"Die gebackenen Kartoffeln halbieren, sch\u00e4len und in eine Sch\u00fcssel geben. Mit einer Gabel zerdr\u00fccken, Ricotta hinzuf\u00fcgen, mit Salz und Pfeffer w\u00fcrzen. Das Mehl hinein sieben und in der Mitte eine Kuhle formen. Ein verquirltes Ei dazugeben und alles zu einem weichen Teig verarbeiten.  ","step_images":[116103,116109,116115,116121],"step_has_images":true},{"step_title":"","step_duration":"","step_description":"Den Teig auf eine leicht bemehlte Fl\u00e4che geben und 5 Minuten lang kneten, bis er glatt und geschmeidig ist. Falls er zu feucht ist, mehr Mehl hinzuf\u00fcgen.","step_images":[116127],"step_has_images":true},{"step_title":"","step_duration":"","step_description":"Den Teig in zwei H\u00e4lften teilen. Jede Portion ausrollen und in eine Wurstform bringen. Jede Wurst in etwa 2,5 cm breite St\u00fccke schneiden. Den bemehlten Daumen in die Mitte der Gnocchi dr\u00fccken.  ","step_images":[116133,116139],"step_has_images":true},{"step_title":"","step_duration":"","step_description":"Bemehle deine H\u00e4nde und lass die Gnocchi vorsichtig in einem gro\u00dfen Topf mit kochendem Salzwasser und Oliven\u00f6l fallen lassen. 3-4 Minuten kochen, bis die Gnocchi an der Oberfl\u00e4che schwimmen. Absch\u00f6pfen und in eine Bratpfanne mit Oliven\u00f6l geben. ","step_images":[116145,116073],"step_has_images":true},{"step_title":"","step_duration":"","step_description":"Dill und Knoblauch \u00fcber die Gnocchi streuen. Sobald die Gnocchi ihre Farbe \u00e4ndern, wenden. Paprika, Butter und Speck hinzugeben. Die Erbsen und Zitronenschale hinzuf\u00fcgen. Zusammen f\u00fcr etwa 5 Minuten kochen. Parmesansp\u00e4ne \u00fcber die Gnocchi streuen und sofort servieren.   ","step_images":[116079,116085,116091,116097],"step_has_images":true}],"nutritions":[{"nutrition_name":"Kalorien","nutrition_value":"503 kcal","nutrition_extra_info":"","google_rich_meta_field":false},{"nutrition_name":"Fette","nutrition_value":"30.1 g","nutrition_extra_info":"","google_rich_meta_field":false},{"nutrition_name":"Kohlenhydrate","nutrition_value":"36.6 g","nutrition_extra_info":"","google_rich_meta_field":false},{"nutrition_name":"Proteine","nutrition_value":"24.8 g","nutrition_extra_info":"","google_rich_meta_field":false}],"show_selected_posts_as_relative":[5819,5462,5775,5743,5455],"show_featured_recipes_slider":false,"featured_recipes":null,"featured_recipes_background_image":null,"featured_recipes_layout_type":"mixed","make_featured_recipes_fixed_width":false,"background_image":null,"background_image_size":"default","parallax_background":"default","enable_custom_header_settings":false,"top_menu_type":"version_1","logo_image":null,"logo_image_width":210},"related_recipe_ids":[5819,5462,5775,5743,5455],"default_slug":"gluten-free-ricotta-gnocchi","translations":[{"language":"en","id":5833,"slug":"gluten-free-ricotta-gnocchi","url":"https:\/\/www.thegfrecipes.com\/recipe\/gluten-free-ricotta-gnocchi"},{"language":"ro","id":50209,"slug":"gnocchi-fara-gluten-cu-ricotta","url":"https:\/\/www.thegfrecipes.com\/ro\/reteta\/gnocchi-fara-gluten-cu-ricotta"},{"language":"it","id":119632,"slug":"gluten-free-ricotta-gnocchi","url":"https:\/\/www.thegfrecipes.com\/it\/ricetta\/gluten-free-ricotta-gnocchi"},{"language":"es","id":119696,"slug":"noquis-sin-gluten","url":"https:\/\/www.thegfrecipes.com\/es\/receta\/noquis-sin-gluten"},{"language":"de","id":119783,"slug":"glutenfreie-ricotta-gnocchi","url":"https:\/\/www.thegfrecipes.com\/de\/rezept\/glutenfreie-ricotta-gnocchi"},{"language":"fr","id":119983,"slug":"gnocchis-a-la-ricotta-sans-gluten","url":"https:\/\/www.thegfrecipes.com\/fr\/recette\/gnocchis-a-la-ricotta-sans-gluten"},{"language":"tr","id":125428,"slug":"glutensiz-ricotta-gnocchi","url":"https:\/\/www.thegfrecipes.com\/tr\/yemek-tarifi\/glutensiz-ricotta-gnocchi"}],"_links":{"self":[{"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/119783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe"}],"about":[{"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/types\/osetin_recipe"}],"author":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/comments?post=119783"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/5455"},{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/5743"},{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/5775"},{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/5462"},{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/osetin_recipe\/5819"}],"acf:term":[{"embeddable":true,"taxonomy":"recipe_feature","href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/recipe_feature\/1614"},{"embeddable":true,"taxonomy":"recipe_cuisine","href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/recipe_cuisine\/1613"},{"embeddable":true,"taxonomy":"category","href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/categories\/1635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/media\/116151"}],"wp:attachment":[{"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/media?parent=119783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/categories?post=119783"},{"taxonomy":"recipe_feature","embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/recipe_feature?post=119783"},{"taxonomy":"recipe_ingredient","embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/recipe_ingredient?post=119783"},{"taxonomy":"recipe_cuisine","embeddable":true,"href":"https:\/\/www.thegfrecipes.com\/de\/wp-json\/wp\/v2\/recipe_cuisine?post=119783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}